{"id":6921,"count":0,"description":"Baustellen k\u00f6nnen sehr gef\u00e4hrliche Orte sein.\u00a0 Ein wichtiger Bestandteil der Erhaltung einer sicheren Arbeitsumgebung ist, Zugangspunkte f\u00fcr Fu\u00dfg\u00e4nger oder Arbeiter auf der Baustelle zu definieren.\u00a0 IPG bietet eine komplette Palette an Absperrb\u00e4ndern, Markierungsb\u00e4ndern und weiterer Sicherheitsausr\u00fcstung, die an Baustellen verwendet werden kann. Damit ist IPG eine zuverl\u00e4ssige Quelle f\u00fcr Produkte f\u00fcr das Baugewerbe aus einer Hand.","link":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/","name":"Baustellensicherheit","slug":"baustellensicherheit-de","taxonomy":"associated_application","parent":6880,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.1 (Yoast SEO v27.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Baustellensicherheit - IPG<\/title>\n<meta name=\"description\" content=\"IPG bietet eine komplette Palette an Absperrb\u00e4ndern, Markierungsb\u00e4ndern und weiterer Sicherheitsausr\u00fcstung f\u00fcr den Einsatz in Baustellen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baustellensicherheit Archives\" \/>\n<meta property=\"og:description\" content=\"IPG bietet eine komplette Palette an Absperrb\u00e4ndern, Markierungsb\u00e4ndern und weiterer Sicherheitsausr\u00fcstung f\u00fcr den Einsatz in Baustellen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/\" \/>\n<meta property=\"og:site_name\" content=\"IPG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@IPGtape\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/de\\\/associated_application\\\/baustellensicherheit-de\\\/\",\"url\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/de\\\/associated_application\\\/baustellensicherheit-de\\\/\",\"name\":\"Baustellensicherheit - IPG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/#website\"},\"description\":\"IPG bietet eine komplette Palette an Absperrb\u00e4ndern, Markierungsb\u00e4ndern und weiterer Sicherheitsausr\u00fcstung f\u00fcr den Einsatz in Baustellen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/de\\\/associated_application\\\/baustellensicherheit-de\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/de\\\/associated_application\\\/baustellensicherheit-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bauwesen\",\"item\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/de\\\/associated_application\\\/bauwesen-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Baustellensicherheit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/#website\",\"url\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/\",\"name\":\"IPG\",\"description\":\"Global Leader in Packaging and Protective Solutions\",\"publisher\":{\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/#organization\",\"name\":\"IPG\",\"url\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IPG-logo-2.png\",\"contentUrl\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/IPG-logo-2.png\",\"width\":60,\"height\":60,\"caption\":\"IPG\"},\"image\":{\"@id\":\"https:\\\/\\\/itape-qa-wp.itape.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/intertape\",\"https:\\\/\\\/x.com\\\/IPGtape\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/intertape-polymer-group\",\"https:\\\/\\\/www.instagram.com\\\/ipgtape\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/IPGtape\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Baustellensicherheit - IPG","description":"IPG bietet eine komplette Palette an Absperrb\u00e4ndern, Markierungsb\u00e4ndern und weiterer Sicherheitsausr\u00fcstung f\u00fcr den Einsatz in Baustellen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/","og_locale":"de_DE","og_type":"article","og_title":"Baustellensicherheit Archives","og_description":"IPG bietet eine komplette Palette an Absperrb\u00e4ndern, Markierungsb\u00e4ndern und weiterer Sicherheitsausr\u00fcstung f\u00fcr den Einsatz in Baustellen.","og_url":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/","og_site_name":"IPG","twitter_card":"summary_large_image","twitter_site":"@IPGtape","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/","url":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/","name":"Baustellensicherheit - IPG","isPartOf":{"@id":"https:\/\/itape-qa-wp.itape.com\/#website"},"description":"IPG bietet eine komplette Palette an Absperrb\u00e4ndern, Markierungsb\u00e4ndern und weiterer Sicherheitsausr\u00fcstung f\u00fcr den Einsatz in Baustellen.","breadcrumb":{"@id":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/baustellensicherheit-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/itape-qa-wp.itape.com\/home\/"},{"@type":"ListItem","position":2,"name":"Bauwesen","item":"https:\/\/itape-qa-wp.itape.com\/de\/associated_application\/bauwesen-de\/"},{"@type":"ListItem","position":3,"name":"Baustellensicherheit"}]},{"@type":"WebSite","@id":"https:\/\/itape-qa-wp.itape.com\/#website","url":"https:\/\/itape-qa-wp.itape.com\/","name":"IPG","description":"Global Leader in Packaging and Protective Solutions","publisher":{"@id":"https:\/\/itape-qa-wp.itape.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/itape-qa-wp.itape.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/itape-qa-wp.itape.com\/#organization","name":"IPG","url":"https:\/\/itape-qa-wp.itape.com\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/itape-qa-wp.itape.com\/#\/schema\/logo\/image\/","url":"https:\/\/itape-qa-wp.itape.com\/wp-content\/uploads\/2024\/06\/IPG-logo-2.png","contentUrl":"https:\/\/itape-qa-wp.itape.com\/wp-content\/uploads\/2024\/06\/IPG-logo-2.png","width":60,"height":60,"caption":"IPG"},"image":{"@id":"https:\/\/itape-qa-wp.itape.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/intertape","https:\/\/x.com\/IPGtape","https:\/\/www.linkedin.com\/company\/intertape-polymer-group","https:\/\/www.instagram.com\/ipgtape","https:\/\/www.youtube.com\/user\/IPGtape"]}]}},"_links":{"self":[{"href":"https:\/\/itape-qa-wp.itape.com\/de\/wp-json\/wp\/v2\/associated_application\/6921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/itape-qa-wp.itape.com\/de\/wp-json\/wp\/v2\/associated_application"}],"about":[{"href":"https:\/\/itape-qa-wp.itape.com\/de\/wp-json\/wp\/v2\/taxonomies\/associated_application"}],"up":[{"embeddable":true,"href":"https:\/\/itape-qa-wp.itape.com\/de\/wp-json\/wp\/v2\/associated_application\/6880"}],"wp:post_type":[{"href":"https:\/\/itape-qa-wp.itape.com\/de\/wp-json\/wp\/v2\/product?associated_application=6921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}